{"id":1930,"date":"2024-11-08T06:32:06","date_gmt":"2024-11-08T06:32:06","guid":{"rendered":"https:\/\/chandelier-yc.com\/?p=1930"},"modified":"2024-11-08T06:32:06","modified_gmt":"2024-11-08T06:32:06","slug":"how-low-should-a-chandelier-hang-over-a-table","status":"publish","type":"post","link":"https:\/\/chandelier-yc.com\/pt\/how-low-should-a-chandelier-hang-over-a-table\/","title":{"rendered":"A que altura deve um candelabro pender sobre uma mesa?"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Alternar<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/chandelier-yc.com\/pt\/how-low-should-a-chandelier-hang-over-a-table\/#Ensuring_the_Perfect_Height_How_Low_Should_a_Chandelier_Hang_Over_a_Table%E2%80%8B\" >Assegurar a altura perfeita: a que altura deve um candelabro pender sobre uma mesa?<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/chandelier-yc.com\/pt\/how-low-should-a-chandelier-hang-over-a-table\/#Factors_to_Consider\" >Factores a considerar<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/chandelier-yc.com\/pt\/how-low-should-a-chandelier-hang-over-a-table\/#Determining_the_Ideal_Height\" >Determina\u00e7\u00e3o da altura ideal<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Ensuring_the_Perfect_Height_How_Low_Should_a_Chandelier_Hang_Over_a_Table%E2%80%8B\"><\/span>Assegurar a altura perfeita: a que altura deve um candelabro pender sobre uma mesa?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p data-sourcepos=\"3:1-3:362\">A altura a que um candelabro deve ser pendurado sobre uma mesa pode elevar o ambiente da sua sala de jantar. No entanto, pendur\u00e1-lo \u00e0 altura correta \u00e9 crucial. Um candeeiro demasiado baixo ou demasiado alto pode perturbar a harmonia visual do espa\u00e7o. Este guia ir\u00e1 ajud\u00e1-lo a determinar a altura ideal para o seu candeeiro, considerando factores como a altura do teto, o tamanho da mesa e a prefer\u00eancia pessoal.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Factors_to_Consider\"><\/span>Factores a considerar<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p data-sourcepos=\"7:1-7:60\">A que altura deve um candelabro pender sobre uma mesa, considere estes factores:<\/p>\n<ul data-sourcepos=\"9:1-13:0\">\n<li data-sourcepos=\"9:1-9:157\"><strong>Altura do teto:<\/strong> Um teto de 3 metros oferece um espa\u00e7o amplo para um candelabro. No entanto, a altura do candeeiro deve ser proporcional \u00e0 divis\u00e3o.<\/li>\n<li data-sourcepos=\"10:1-10:148\"><strong>Tamanho do quarto:<\/strong> O tamanho da sala de jantar ir\u00e1 influenciar o tamanho e o estilo do candeeiro. Uma sala maior pode acomodar um candeeiro maior.<\/li>\n<li data-sourcepos=\"11:1-11:107\"><strong>Estilo de candelabro:<\/strong> O design e o tamanho do candeeiro tamb\u00e9m afectam a altura ideal de suspens\u00e3o.<\/li>\n<li data-sourcepos=\"12:1-13:0\"><strong>Prefer\u00eancia pessoal:<\/strong> Em \u00faltima an\u00e1lise, a est\u00e9tica e a funcionalidade desejadas para o seu espa\u00e7o de refei\u00e7\u00f5es devem orientar a sua decis\u00e3o.<\/li>\n<\/ul>\n<h3 data-sourcepos=\"14:1-14:32\"><span class=\"ez-toc-section\" id=\"Determining_the_Ideal_Height\"><\/span>Determina\u00e7\u00e3o da altura ideal<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p data-sourcepos=\"16:1-16:196\">Uma regra geral \u00e9 pendurar o candeeiro cerca de 30-36 polegadas acima da mesa de jantar. No entanto, isto pode variar consoante as circunst\u00e2ncias espec\u00edficas. Aqui est\u00e1 uma abordagem mais precisa:<\/p>\n<ol data-sourcepos=\"18:1-21:0\">\n<li data-sourcepos=\"18:1-18:71\"><strong>Medir a mesa:<\/strong> Determine o di\u00e2metro da sua mesa de jantar.<\/li>\n<li data-sourcepos=\"19:1-19:145\"><strong>Calcular a altura:<\/strong> Adicione 30-36 polegadas ao di\u00e2metro da mesa. Isto dar-lhe-\u00e1 a altura ideal para a base do candelabro.<\/li>\n<li data-sourcepos=\"20:1-21:0\"><strong>Ajustar \u00e0 altura do teto:<\/strong> Se tiver um teto mais alto, poder\u00e1 querer pendurar o candelabro ligeiramente mais alto para manter o equil\u00edbrio visual.<\/li>\n<\/ol>","protected":false},"excerpt":{"rendered":"<p>Assegurar a altura perfeita: a que altura deve um candelabro pender sobre uma mesa? A altura a que um candelabro deve ser pendurado sobre uma mesa pode elevar o ambiente da sua sala de jantar. No entanto, pendur\u00e1-lo \u00e0 altura correta \u00e9 crucial. Um candeeiro demasiado baixo ou demasiado alto pode perturbar a harmonia visual da sala de jantar.","protected":false},"author":3,"featured_media":1931,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/chandelier-yc.com\/pt\/wp-json\/wp\/v2\/posts\/1930"}],"collection":[{"href":"https:\/\/chandelier-yc.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chandelier-yc.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chandelier-yc.com\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/chandelier-yc.com\/pt\/wp-json\/wp\/v2\/comments?post=1930"}],"version-history":[{"count":1,"href":"https:\/\/chandelier-yc.com\/pt\/wp-json\/wp\/v2\/posts\/1930\/revisions"}],"predecessor-version":[{"id":1932,"href":"https:\/\/chandelier-yc.com\/pt\/wp-json\/wp\/v2\/posts\/1930\/revisions\/1932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chandelier-yc.com\/pt\/wp-json\/wp\/v2\/media\/1931"}],"wp:attachment":[{"href":"https:\/\/chandelier-yc.com\/pt\/wp-json\/wp\/v2\/media?parent=1930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chandelier-yc.com\/pt\/wp-json\/wp\/v2\/categories?post=1930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chandelier-yc.com\/pt\/wp-json\/wp\/v2\/tags?post=1930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}